{"id":34,"count":2,"description":"","link":"https:\/\/gesund-in-balance.de\/en\/category\/empowerment-en\/","name":"Empowerment","slug":"empowerment-en","taxonomy":"category","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/gesund-in-balance.de\/en\/wp-json\/wp\/v2\/categories\/34","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gesund-in-balance.de\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/gesund-in-balance.de\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/gesund-in-balance.de\/en\/wp-json\/wp\/v2\/posts?categories=34"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}